{"id":599,"date":"2018-08-03T08:34:36","date_gmt":"2018-08-03T08:34:36","guid":{"rendered":"https:\/\/northlandinjurylaw.com\/?p=599"},"modified":"2024-05-23T14:09:18","modified_gmt":"2024-05-23T14:09:18","slug":"tu-riesgo-de-morir-se-multiplico-por-5-hoy-si-estas-haciendo-esto","status":"publish","type":"post","link":"https:\/\/northlandinjurylaw.com\/es\/blog\/tu-riesgo-de-morir-se-multiplico-por-5-hoy-si-estas-haciendo-esto\/","title":{"rendered":"Su riesgo de morir se ha multiplicado por 5 hoy, si hace esto"},"content":{"rendered":"<p>Cuando retrocedes el reloj un <a href=\"http:\/\/www.inc.com\/thomas-koulopoulos\/this-may-be-biggest-economic-social-shift-of-last-100-years-are-you-ready.html?cid=search\" target=\"_blank\" rel=\"noopener\">cien a\u00f1os<\/a> y te preguntas: \"\u00bfQu\u00e9 era lo que m\u00e1s miedo daba de c\u00f3mo viv\u00eda la gente?\", \u00bfqu\u00e9 te viene a la mente?<\/p>\n<p>No, \u00a1no es la falta de un smartphone!<\/p>\n<p>En cambio, consideremos que en 1918 la gripe espa\u00f1ola mat\u00f3 al 5% de la poblaci\u00f3n mundial e infect\u00f3 a casi el 25%. Fue la pandemia m\u00e1s mort\u00edfera de la historia.<\/p>\n<p>As\u00ed que, teniendo esto en cuenta, podr\u00eda sugerir que las vacunas y otros beneficios de la medicina moderna ocupar\u00edan un lugar bastante alto para la mayor\u00eda de nosotros.<\/p>\n<p>Sin embargo, en 1918, probablemente habr\u00edas aceptado ese riesgo como parte de la vida. Al fin y al cabo, no se pod\u00eda hacer nada contra la gripe, salvo aislarse completamente de cualquier otro ser humano.<\/p>\n<p>Formar parte de la sociedad significaba participar en actividades intr\u00ednsecamente muy arriesgadas, como el trabajo, la escuela, las compras, el cuidado de la familia y la vida social.<\/p>\n<p>As\u00ed funcionaba el mundo.<\/p>\n<p>Y, sin embargo, hoy miramos a aquellos habitantes de principios del siglo XX con l\u00e1stima por el alto coste que tuvieron que pagar sin el beneficio de los productos farmac\u00e9uticos y la tecnolog\u00eda m\u00e9dica actuales.<\/p>\n<p>Ahora, adelante el reloj 100 a\u00f1os. \u00bfQu\u00e9 dir\u00e1n los habitantes de 2118 que es lo m\u00e1s aterrador de la vida que llevamos ahora? <strong>\"Se podr\u00eda afirmar f\u00e1cilmente que los veh\u00edculos son la principal causa de muerte de quienes poseen un autom\u00f3vil o interact\u00faan con \u00e9l\".<\/strong><\/p>\n<p>De todas las actividades en las que participamos, conducir y compartir nuestro mundo con veh\u00edculos es lo que m\u00e1s riesgo entra\u00f1a para la mayor\u00eda de nosotros. Y hoy, 2 de agosto, es el d\u00eda m\u00e1s mort\u00edfero del a\u00f1o en incidentes vehiculares. S\u00f3lo en Estados Unidos, m\u00e1s de 500 personas morir\u00e1n antes de que acabe el d\u00eda. Eso es unas cinco veces m\u00e1s que la media matem\u00e1tica basada en 38.000 muertes anuales.<\/p>\n<p>Los veh\u00edculos son responsables de 1,3 millones de muertes al a\u00f1o en todo el mundo, lo que los sit\u00faa como la 10\u00aa causa de muerte y la \u00fanica no relacionada con enfermedades entre las 10 primeras. El total de heridos por accidentes de tr\u00e1fico supera los 50 millones.<\/p>\n<p>Esto es lo sorprendente. En mi reciente libro <a href=\"http:\/\/a.co\/6wLEkIw\" target=\"_blank\" rel=\"noopener\">Revelar lo invisible,<\/a> Se\u00f1alo que si se ajusta al hecho de que s\u00f3lo hay mil millones de veh\u00edculos en todo el mundo, en comparaci\u00f3n con el hecho de que los siete mil millones de personas corren el riesgo de adquirir cualquiera de los factores de riesgo de las nueve enfermedades, se podr\u00eda afirmar f\u00e1cilmente que los veh\u00edculos son la principal causa de muerte para aquellos que poseen o interact\u00faan con un autom\u00f3vil.<\/p>\n<p>Aun as\u00ed, ninguno de nosotros se lo pensar\u00eda dos veces antes de correr ese riesgo; ni siquiera hoy, cuando las probabilidades de que formemos parte de esa estad\u00edstica son cinco veces superiores a la media.<\/p>\n<p>Se trata de una carnicer\u00eda a escala masiva. Para ponerlo en perspectiva, en s\u00f3lo dos a\u00f1os el n\u00famero de muertes debidas a accidentes de tr\u00e1fico es mayor que el n\u00famero de muertos estadounidenses durante todo el conflicto y la guerra de Vietnam.<\/p>\n<p>Podr\u00eda terminar la columna aqu\u00ed, pero si ha seguido alguno de mis escritos, probablemente sepa a d\u00f3nde quiero llegar con esto.<\/p>\n<p>Estamos a pocas d\u00e9cadas de ver el final de la era de los veh\u00edculos conducidos por humanos. Los veh\u00edculos aut\u00f3nomos reducir\u00e1n en un 95% el n\u00famero de v\u00edctimas mortales en accidentes de tr\u00e1fico atribuibles a errores humanos. (Para m\u00e1s detalles, consulte un <a href=\"http:\/\/delphigroup.com\/wp-content\/uploads\/2018\/06\/Transportation-2050-Delphi-Group.pdf\" target=\"_blank\" rel=\"noopener\">informe de investigaci\u00f3n sobre el transporte<\/a> publicado recientemente por mi empresa e Ideafarms, con sede en la India). Eso significa salvar m\u00e1s de un mill\u00f3n de vidas al a\u00f1o.<\/p>\n<p>Si sospecha de esto por alguna de las <a href=\"http:\/\/www.inc.com\/thomas-koulopoulos\/ubers-fatal-incident-isnt-end-its-beginning.html?cid=search\" target=\"_blank\" rel=\"noopener\">noticias recientes<\/a> con respecto a los incidentes con coches sin conductor, entonces piense en el hecho de que el mayor impacto de los veh\u00edculos aut\u00f3nomos ser\u00e1 salvar las vidas de sus propios hijos y nietos al tiempo que le permite mantener su propia libertad, independencia y seguridad a medida que envejece.<\/p>\n<p>No cabe duda de que los veh\u00edculos aut\u00f3nomos acaparar\u00e1n mucha m\u00e1s atenci\u00f3n por cada accidente en el que se vean implicados que los veh\u00edculos conducidos por humanos. Pero es crucial tener en cuenta d\u00f3nde est\u00e1 el list\u00f3n actualmente.<\/p>\n<p>Hoy, m\u00e1s de 500 personas pagar\u00e1n el precio m\u00e1s alto de todos para formar parte del mundo civilizado. Algunos viajar\u00e1n de vacaciones. Algunas ser\u00e1n familias. Algunos ser\u00e1n ni\u00f1os. Algunos ser\u00e1n abuelos o quiz\u00e1s padres primerizos. Ni uno solo merece formar parte de una estad\u00edstica que simplemente hemos dado por sentada como parte del funcionamiento del mundo.<\/p>","protected":false},"excerpt":{"rendered":"<p>When you roll the clock back a hundred years and wonder, \u201cWhat was the scariest part of how people lived?\u201d what comes to mind? No, it\u2019s not the lack of a smartphone! Instead, consider that in 1918 the Spanish flu killed 5 percent of the world\u2019s population and infected nearly 25 percent. It was the &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/northlandinjurylaw.com\/es\/blog\/tu-riesgo-de-morir-se-multiplico-por-5-hoy-si-estas-haciendo-esto\/\" class=\"more-link\">Seguir leyendo<span class=\"screen-reader-text\"> &#8220;Your Risk Of Dying Increased 5-Fold Today, If You Are Doing This&#8221;<\/span><\/a><\/p>","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[309,325],"class_list":["post-599","post","type-post","status-publish","format-standard","hentry","category-news","tag-auto-accident-kansas-city","tag-driver-safety","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Your Risk Of Dying Increased 5-Fold Today, If You Are Doing This - Northland Injury Law<\/title>\n<meta name=\"description\" content=\"When you roll the clock back a hundred years and wonder, \u201cWhat was the scariest part of how people lived?\u201d what comes to mind? No, it\u2019s not the lack of a smartphone! Instead, consider that in 1918 the Spanish flu killed 5 percent of the world\u2019s population and infected nearly 25 percent. It was the single deadliest pandemic in recorded history. \u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/northlandinjurylaw.com\/es\/blog\/tu-riesgo-de-morir-se-multiplico-por-5-hoy-si-estas-haciendo-esto\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Your Risk Of Dying Increased 5-Fold Today, If You Are Doing This - Northland Injury Law\" \/>\n<meta property=\"og:description\" content=\"When you roll the clock back a hundred years and wonder, \u201cWhat was the scariest part of how people lived?\u201d what comes to mind? No, it\u2019s not the lack of a smartphone! Instead, consider that in 1918 the Spanish flu killed 5 percent of the world\u2019s population and infected nearly 25 percent. It was the single deadliest pandemic in recorded history. \u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/northlandinjurylaw.com\/es\/blog\/tu-riesgo-de-morir-se-multiplico-por-5-hoy-si-estas-haciendo-esto\/\" \/>\n<meta property=\"og:site_name\" content=\"Northland Injury Law\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/accidentinjurylawyers\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-03T08:34:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-23T14:09:18+00:00\" \/>\n<meta name=\"author\" content=\"Eric Bartlett\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eric Bartlett\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Su riesgo de morir aument\u00f3 5 veces hoy, si usted est\u00e1 haciendo esto - Northland Injury Law","description":"Cuando retrocedemos el reloj cien a\u00f1os y nos preguntamos: \"\u00bfQu\u00e9 era lo que m\u00e1s miedo daba de c\u00f3mo viv\u00eda la gente?\", \u00bfqu\u00e9 nos viene a la mente? No, \u00a1no es la falta de un smartphone! Piense que en 1918 la gripe espa\u00f1ola mat\u00f3 al 5% de la poblaci\u00f3n mundial e infect\u00f3 a casi el 25%. Fue la pandemia m\u00e1s mort\u00edfera de la historia. ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/northlandinjurylaw.com\/es\/blog\/tu-riesgo-de-morir-se-multiplico-por-5-hoy-si-estas-haciendo-esto\/","og_locale":"es_MX","og_type":"article","og_title":"Your Risk Of Dying Increased 5-Fold Today, If You Are Doing This - Northland Injury Law","og_description":"When you roll the clock back a hundred years and wonder, \u201cWhat was the scariest part of how people lived?\u201d what comes to mind? No, it\u2019s not the lack of a smartphone! Instead, consider that in 1918 the Spanish flu killed 5 percent of the world\u2019s population and infected nearly 25 percent. It was the single deadliest pandemic in recorded history. \u2026","og_url":"https:\/\/northlandinjurylaw.com\/es\/blog\/tu-riesgo-de-morir-se-multiplico-por-5-hoy-si-estas-haciendo-esto\/","og_site_name":"Northland Injury Law","article_publisher":"https:\/\/www.facebook.com\/accidentinjurylawyers\/","article_published_time":"2018-08-03T08:34:36+00:00","article_modified_time":"2024-05-23T14:09:18+00:00","author":"Eric Bartlett","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eric Bartlett","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/northlandinjurylaw.com\/blog\/your-risk-of-dying-increased-5-fold-today-if-you-are-doing-this\/#article","isPartOf":{"@id":"https:\/\/northlandinjurylaw.com\/blog\/your-risk-of-dying-increased-5-fold-today-if-you-are-doing-this\/"},"author":{"name":"Eric Bartlett","@id":"https:\/\/northlandinjurylaw.com\/#\/schema\/person\/1e35848aa80e77f1c0b4159d4073bc20"},"headline":"Your Risk Of Dying Increased 5-Fold Today, If You Are Doing This","datePublished":"2018-08-03T08:34:36+00:00","dateModified":"2024-05-23T14:09:18+00:00","mainEntityOfPage":{"@id":"https:\/\/northlandinjurylaw.com\/blog\/your-risk-of-dying-increased-5-fold-today-if-you-are-doing-this\/"},"wordCount":727,"commentCount":0,"publisher":{"@id":"https:\/\/northlandinjurylaw.com\/#organization"},"keywords":["auto accident kansas city","driver safety"],"articleSection":["News"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/northlandinjurylaw.com\/blog\/your-risk-of-dying-increased-5-fold-today-if-you-are-doing-this\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/northlandinjurylaw.com\/blog\/your-risk-of-dying-increased-5-fold-today-if-you-are-doing-this\/","url":"https:\/\/northlandinjurylaw.com\/blog\/your-risk-of-dying-increased-5-fold-today-if-you-are-doing-this\/","name":"Su riesgo de morir aument\u00f3 5 veces hoy, si usted est\u00e1 haciendo esto - Northland Injury Law","isPartOf":{"@id":"https:\/\/northlandinjurylaw.com\/#website"},"datePublished":"2018-08-03T08:34:36+00:00","dateModified":"2024-05-23T14:09:18+00:00","description":"Cuando retrocedemos el reloj cien a\u00f1os y nos preguntamos: \"\u00bfQu\u00e9 era lo que m\u00e1s miedo daba de c\u00f3mo viv\u00eda la gente?\", \u00bfqu\u00e9 nos viene a la mente? No, \u00a1no es la falta de un smartphone! Piense que en 1918 la gripe espa\u00f1ola mat\u00f3 al 5% de la poblaci\u00f3n mundial e infect\u00f3 a casi el 25%. Fue la pandemia m\u00e1s mort\u00edfera de la historia. ...","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/northlandinjurylaw.com\/blog\/your-risk-of-dying-increased-5-fold-today-if-you-are-doing-this\/"]}]},{"@type":"WebSite","@id":"https:\/\/northlandinjurylaw.com\/#website","url":"https:\/\/northlandinjurylaw.com\/","name":"Ley de lesiones de Northland","description":"","publisher":{"@id":"https:\/\/northlandinjurylaw.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/northlandinjurylaw.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/northlandinjurylaw.com\/#organization","name":"Ley de lesiones de Northland","url":"https:\/\/northlandinjurylaw.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/northlandinjurylaw.com\/#\/schema\/logo\/image\/","url":"https:\/\/northlandinjurylaw.com\/wp-content\/uploads\/2024\/05\/logo.jpg","contentUrl":"https:\/\/northlandinjurylaw.com\/wp-content\/uploads\/2024\/05\/logo.jpg","width":415,"height":103,"caption":"Northland Injury Law"},"image":{"@id":"https:\/\/northlandinjurylaw.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/accidentinjurylawyers\/","https:\/\/www.linkedin.com\/company\/northland-injury-law","https:\/\/www.instagram.com\/northlandinjurylaw\/","https:\/\/www.youtube.com\/@northlandinjurylaw4755","https:\/\/www.yelp.com\/biz\/northland-injury-law-kansas-city","https:\/\/www.lawinfo.com\/lawfirm\/missouri\/kansas-city\/northland-injury-law\/ca10cabc-467c-446b-bfc0-f673053baf63.html","https:\/\/profiles.superlawyers.com\/missouri\/kansas-city\/lawfirm\/northland-injury-law\/ca10cabc-467c-446b-bfc0-f673053baf63.html","https:\/\/lawyers.findlaw.com\/profile\/view\/2362635_1","https:\/\/reviews.birdeye.com\/northland-injury-law-164779247415291","https:\/\/localspark.com\/listings\/legal-services\/kansas-city-mo\/northland-injury-law-5600-ne-antioch-rd-kansas-city-mo-64119\/","https:\/\/www.zoominfo.com\/p\/Stephen-Mowry\/126980529","https:\/\/www.datanyze.com\/companies\/northland-injury-law\/358568082"]},{"@type":"Person","@id":"https:\/\/northlandinjurylaw.com\/#\/schema\/person\/1e35848aa80e77f1c0b4159d4073bc20","name":"Eric Bartlett","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bf253cf71e20f6e1cffd8b8f42de35214279011bf47dbcb56d2ffc79a4f5d414?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf253cf71e20f6e1cffd8b8f42de35214279011bf47dbcb56d2ffc79a4f5d414?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf253cf71e20f6e1cffd8b8f42de35214279011bf47dbcb56d2ffc79a4f5d414?s=96&d=mm&r=g","caption":"Eric Bartlett"},"url":"https:\/\/northlandinjurylaw.com\/es\/author\/eric-bartlett-2\/"}]}},"_links":{"self":[{"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/posts\/599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/comments?post=599"}],"version-history":[{"count":1,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/posts\/599\/revisions"}],"predecessor-version":[{"id":2705,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/posts\/599\/revisions\/2705"}],"wp:attachment":[{"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/media?parent=599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/categories?post=599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/tags?post=599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}