{"id":2164,"date":"2019-04-03T10:08:32","date_gmt":"2019-04-03T10:08:32","guid":{"rendered":"https:\/\/northlandinjurylaw.com\/?p=2164"},"modified":"2024-05-23T14:09:17","modified_gmt":"2024-05-23T14:09:17","slug":"la-policia-del-condado-de-jackson-sigue-a-la-cabeza-de-missouri-en-numero-de-detenciones-por-alcoholemia","status":"publish","type":"post","link":"https:\/\/northlandinjurylaw.com\/es\/blog\/la-policia-del-condado-de-jackson-sigue-a-la-cabeza-de-missouri-en-numero-de-detenciones-por-alcoholemia\/","title":{"rendered":"Trooper en el condado de Jackson sigue liderando Missouri en el n\u00famero de detenciones por DWI"},"content":{"rendered":"<p>Por: Charlie Keegan<\/p>\n<p>LEE'S SUMMIT, Mo. - Cuando se trata de detener a conductores ebrios, ning\u00fan polic\u00eda de la Patrulla Estatal de Carreteras Missouri lo hace mejor que uno del condado de Jackson.<\/p>\n<p>Trooper Aaron Engelhart ha detenido a m\u00e1s personas bajo sospecha de conducir en estado de ebriedad entre los troopers MSHP en tres de los \u00faltimos cuatro a\u00f1os. En sus 6 a\u00f1os de carrera, Engelhart ha realizado 684 detenciones por conducir ebrio. Tuvo la mayor cantidad de arrestos de cualquier trooper en el estado con 175 en 2015, 181 en 2017 y 135 en 2018. En 2016 se rompi\u00f3 la mu\u00f1eca, pero aun as\u00ed termin\u00f3 entre los diez primeros.<\/p>\n<p>Ciento ochenta y uno es el m\u00e1s alto de todos los tiempos para el n\u00famero de arrestos de DWI en un a\u00f1o por un trooper MSHP.<\/p>\n<p>\"Hay gente que conduce por las carreteras de todo el mundo, que son completamente inocentes, que simplemente van y vienen\", explic\u00f3 Engelhart. \"Y potencialmente resulta que su vida se ve interrumpida por alguien que decidi\u00f3 ser ego\u00edsta, b\u00e1sicamente\".<\/p>\n<p>Las estad\u00edsticas del estado en 2017 muestran que conducir ebrio represent\u00f3 aproximadamente el 15 por ciento de todas las muertes de tr\u00e1fico en las carreteras de Missouri. Los agentes dijeron que cada una de esas 122 muertes relacionadas con la conducci\u00f3n bajo los efectos del alcohol podr\u00eda haberse evitado si los conductores hubieran planificado con antelaci\u00f3n para encontrar un camino diferente a casa.<\/p>\n<p>\"Demasiada gente sigue tomando la mala decisi\u00f3n de conducir bajo los efectos del alcohol. Es costoso. Si te metes en un accidente en el que alguien resulta herido o muerto, pagar\u00e1s por ello el resto de tu vida\", dijo el sargento Collin Stosberg del MSHP.<\/p>\n<p>Engelhart no tiene una f\u00f3rmula m\u00e1gica para encontrar a conductores ebrios. Dice que simplemente hace de la b\u00fasqueda de conductores ebrios una prioridad. Puede tener algunas ventajas, ya que trabaja de noche la mitad del a\u00f1o y tiene su base en el condado de Jackson, el segundo m\u00e1s poblado del estado.<\/p>\n<p>Dijo que desde que estaba en la academia, para \u00e9l ha sido un reto personal mantener la seguridad de las carreteras retirando de ellas a los conductores ebrios.<\/p>\n<p>Durante un paseo, dijo a 41 Action News que no para a todos los coches. Est\u00e1 atento a ciertas infracciones y trata de ser eficiente. Uno de cada tres coches que detuvo en 2018 condujo a un arresto por DWI.<\/p>\n<p>\"El objetivo final es no tener que hacerlo, si no tengo que detener a nadie que haga esto. Es un delito completamente evitable\", dijo Engelhart.<\/p>\n<p>Stosberg dijo que si alguien decide conducir ebrio en el condado de Jackson, no es una cuesti\u00f3n de si, pero cuando Engelhart o uno de sus compa\u00f1eros de polic\u00eda arrestar\u00e1 a esa persona.<\/p>\n<p>Si usted ha sufrido lesiones en un accidente de coche causado por un conductor ebrio o distra\u00eddo, llame a Northland Injury Law en <a href=\"tel:8164004878\">816-400-4878<\/a> hable hoy mismo con un abogado especializado en accidentes de tr\u00e1fico Missouri para que le ayude a obtener la indemnizaci\u00f3n que necesita. Un abogado con experiencia en lesiones personales puede aliviar parte de la carga mediante la participaci\u00f3n en la investigaci\u00f3n de los hechos, la recopilaci\u00f3n de la documentaci\u00f3n necesaria, y la elaboraci\u00f3n de demandas concisas y exhaustivas para la soluci\u00f3n de su reclamo.<\/p>","protected":false},"excerpt":{"rendered":"<p>By: Charlie Keegan LEE\u2019S SUMMIT, Mo. \u2014 When it comes to stopping drunk drivers, no Missouri State Highway Patrol trooper does it better than one in Jackson County. Trooper Aaron Engelhart has arrested the most people on suspicion of driving while intoxicated among MSHP troopers in three of the past four years. In his 6-year &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/northlandinjurylaw.com\/es\/blog\/la-policia-del-condado-de-jackson-sigue-a-la-cabeza-de-missouri-en-numero-de-detenciones-por-alcoholemia\/\" class=\"more-link\">Seguir leyendo<span class=\"screen-reader-text\"> &#8220;Trooper in Jackson County continues to lead Missouri in number of DWI arrests&#8221;<\/span><\/a><\/p>","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2164","post","type-post","status-publish","format-standard","hentry","category-car-accidents","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trooper in Jackson County continues to lead Missouri in number of DWI arrests - Northland Injury Law<\/title>\n<meta name=\"description\" content=\"By: Charlie Keegan LEE\u2019S SUMMIT, Mo. \u2014 When it comes to stopping drunk drivers, no Missouri State Highway Patrol trooper does it better than one in Jackson County. Trooper Aaron Engelhart has arrested the most people on suspicion of driving while intoxicated among MSHP troopers in three of the past four years. In his 6-year\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/northlandinjurylaw.com\/es\/blog\/la-policia-del-condado-de-jackson-sigue-a-la-cabeza-de-missouri-en-numero-de-detenciones-por-alcoholemia\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trooper in Jackson County continues to lead Missouri in number of DWI arrests - Northland Injury Law\" \/>\n<meta property=\"og:description\" content=\"By: Charlie Keegan LEE\u2019S SUMMIT, Mo. \u2014 When it comes to stopping drunk drivers, no Missouri State Highway Patrol trooper does it better than one in Jackson County. Trooper Aaron Engelhart has arrested the most people on suspicion of driving while intoxicated among MSHP troopers in three of the past four years. In his 6-year\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/northlandinjurylaw.com\/es\/blog\/la-policia-del-condado-de-jackson-sigue-a-la-cabeza-de-missouri-en-numero-de-detenciones-por-alcoholemia\/\" \/>\n<meta property=\"og:site_name\" content=\"Northland Injury Law\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/accidentinjurylawyers\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-03T10:08:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-23T14:09:17+00:00\" \/>\n<meta name=\"author\" content=\"Eric Bartlett\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eric Bartlett\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trooper en el condado de Jackson sigue liderando Missouri en el n\u00famero de detenciones DWI - Northland Injury Law","description":"Por: Charlie Keegan LEE'S SUMMIT, Mo. - Cuando se trata de detener a conductores ebrios, ning\u00fan polic\u00eda de la Patrulla Estatal de Carreteras Missouri lo hace mejor que uno en el condado de Jackson. El polic\u00eda Aaron Engelhart ha arrestado a la mayor cantidad de personas sospechosas de conducir en estado de ebriedad entre los polic\u00edas de MSHP en tres de los \u00faltimos cuatro a\u00f1os. En sus 6 a\u00f1os...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/northlandinjurylaw.com\/es\/blog\/la-policia-del-condado-de-jackson-sigue-a-la-cabeza-de-missouri-en-numero-de-detenciones-por-alcoholemia\/","og_locale":"es_MX","og_type":"article","og_title":"Trooper in Jackson County continues to lead Missouri in number of DWI arrests - Northland Injury Law","og_description":"By: Charlie Keegan LEE\u2019S SUMMIT, Mo. \u2014 When it comes to stopping drunk drivers, no Missouri State Highway Patrol trooper does it better than one in Jackson County. Trooper Aaron Engelhart has arrested the most people on suspicion of driving while intoxicated among MSHP troopers in three of the past four years. In his 6-year\u2026","og_url":"https:\/\/northlandinjurylaw.com\/es\/blog\/la-policia-del-condado-de-jackson-sigue-a-la-cabeza-de-missouri-en-numero-de-detenciones-por-alcoholemia\/","og_site_name":"Northland Injury Law","article_publisher":"https:\/\/www.facebook.com\/accidentinjurylawyers\/","article_published_time":"2019-04-03T10:08:32+00:00","article_modified_time":"2024-05-23T14:09:17+00:00","author":"Eric Bartlett","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eric Bartlett","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/northlandinjurylaw.com\/blog\/trooper-in-jackson-county-continues-to-lead-missouri-in-number-of-dwi-arrests\/#article","isPartOf":{"@id":"https:\/\/northlandinjurylaw.com\/blog\/trooper-in-jackson-county-continues-to-lead-missouri-in-number-of-dwi-arrests\/"},"author":{"name":"Eric Bartlett","@id":"https:\/\/northlandinjurylaw.com\/#\/schema\/person\/1e35848aa80e77f1c0b4159d4073bc20"},"headline":"Trooper in Jackson County continues to lead Missouri in number of DWI arrests","datePublished":"2019-04-03T10:08:32+00:00","dateModified":"2024-05-23T14:09:17+00:00","mainEntityOfPage":{"@id":"https:\/\/northlandinjurylaw.com\/blog\/trooper-in-jackson-county-continues-to-lead-missouri-in-number-of-dwi-arrests\/"},"wordCount":492,"commentCount":0,"publisher":{"@id":"https:\/\/northlandinjurylaw.com\/#organization"},"articleSection":["Car Accidents"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/northlandinjurylaw.com\/blog\/trooper-in-jackson-county-continues-to-lead-missouri-in-number-of-dwi-arrests\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/northlandinjurylaw.com\/blog\/trooper-in-jackson-county-continues-to-lead-missouri-in-number-of-dwi-arrests\/","url":"https:\/\/northlandinjurylaw.com\/blog\/trooper-in-jackson-county-continues-to-lead-missouri-in-number-of-dwi-arrests\/","name":"Trooper en el condado de Jackson sigue liderando Missouri en el n\u00famero de detenciones DWI - Northland Injury Law","isPartOf":{"@id":"https:\/\/northlandinjurylaw.com\/#website"},"datePublished":"2019-04-03T10:08:32+00:00","dateModified":"2024-05-23T14:09:17+00:00","description":"Por: Charlie Keegan LEE'S SUMMIT, Mo. - Cuando se trata de detener a conductores ebrios, ning\u00fan polic\u00eda de la Patrulla Estatal de Carreteras Missouri lo hace mejor que uno en el condado de Jackson. El polic\u00eda Aaron Engelhart ha arrestado a la mayor cantidad de personas sospechosas de conducir en estado de ebriedad entre los polic\u00edas de MSHP en tres de los \u00faltimos cuatro a\u00f1os. En sus 6 a\u00f1os...","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/northlandinjurylaw.com\/blog\/trooper-in-jackson-county-continues-to-lead-missouri-in-number-of-dwi-arrests\/"]}]},{"@type":"WebSite","@id":"https:\/\/northlandinjurylaw.com\/#website","url":"https:\/\/northlandinjurylaw.com\/","name":"Ley de lesiones de Northland","description":"","publisher":{"@id":"https:\/\/northlandinjurylaw.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/northlandinjurylaw.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/northlandinjurylaw.com\/#organization","name":"Ley de lesiones de Northland","url":"https:\/\/northlandinjurylaw.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/northlandinjurylaw.com\/#\/schema\/logo\/image\/","url":"https:\/\/northlandinjurylaw.com\/wp-content\/uploads\/2024\/05\/logo.jpg","contentUrl":"https:\/\/northlandinjurylaw.com\/wp-content\/uploads\/2024\/05\/logo.jpg","width":415,"height":103,"caption":"Northland Injury Law"},"image":{"@id":"https:\/\/northlandinjurylaw.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/accidentinjurylawyers\/","https:\/\/www.linkedin.com\/company\/northland-injury-law","https:\/\/www.instagram.com\/northlandinjurylaw\/","https:\/\/www.youtube.com\/@northlandinjurylaw4755","https:\/\/www.yelp.com\/biz\/northland-injury-law-kansas-city","https:\/\/www.lawinfo.com\/lawfirm\/missouri\/kansas-city\/northland-injury-law\/ca10cabc-467c-446b-bfc0-f673053baf63.html","https:\/\/profiles.superlawyers.com\/missouri\/kansas-city\/lawfirm\/northland-injury-law\/ca10cabc-467c-446b-bfc0-f673053baf63.html","https:\/\/lawyers.findlaw.com\/profile\/view\/2362635_1","https:\/\/reviews.birdeye.com\/northland-injury-law-164779247415291","https:\/\/localspark.com\/listings\/legal-services\/kansas-city-mo\/northland-injury-law-5600-ne-antioch-rd-kansas-city-mo-64119\/","https:\/\/www.zoominfo.com\/p\/Stephen-Mowry\/126980529","https:\/\/www.datanyze.com\/companies\/northland-injury-law\/358568082"]},{"@type":"Person","@id":"https:\/\/northlandinjurylaw.com\/#\/schema\/person\/1e35848aa80e77f1c0b4159d4073bc20","name":"Eric Bartlett","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bf253cf71e20f6e1cffd8b8f42de35214279011bf47dbcb56d2ffc79a4f5d414?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf253cf71e20f6e1cffd8b8f42de35214279011bf47dbcb56d2ffc79a4f5d414?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf253cf71e20f6e1cffd8b8f42de35214279011bf47dbcb56d2ffc79a4f5d414?s=96&d=mm&r=g","caption":"Eric Bartlett"},"url":"https:\/\/northlandinjurylaw.com\/es\/author\/eric-bartlett-2\/"}]}},"_links":{"self":[{"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/posts\/2164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/comments?post=2164"}],"version-history":[{"count":1,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/posts\/2164\/revisions"}],"predecessor-version":[{"id":2684,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/posts\/2164\/revisions\/2684"}],"wp:attachment":[{"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/media?parent=2164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/categories?post=2164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/tags?post=2164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}