{"id":1283,"date":"2021-11-20T12:27:27","date_gmt":"2021-11-20T12:27:27","guid":{"rendered":"https:\/\/northlandinjurylaw.com\/?p=1283"},"modified":"2024-06-14T07:46:56","modified_gmt":"2024-06-14T07:46:56","slug":"los-kansas-city-chiefs-pagaran-los-gastos-medicos-del-nino-de-5-anos-herido-en-el-accidente-de-britt-reid","status":"publish","type":"post","link":"https:\/\/northlandinjurylaw.com\/es\/blog\/los-kansas-city-chiefs-pagaran-los-gastos-medicos-del-nino-de-5-anos-herido-en-el-accidente-de-britt-reid\/","title":{"rendered":"Kansas City Los Chiefs pagar\u00e1n los gastos m\u00e9dicos del ni\u00f1o de 5 a\u00f1os herido en el accidente de Britt Reid"},"content":{"rendered":"<p>Como abogados de lesiones personales de Northland en Kansas City, nos encontramos constantemente con clientes que sufren lesiones personales cuando se ven implicados en accidentes de tr\u00e1fico. Como padres primero y abogados despu\u00e9s, es importante para nosotros promover la seguridad de los conductores.<\/p>\n<p>Los Kansas City Chiefs anunciaron el viernes que pagar\u00e1n los gastos m\u00e9dicos de la ni\u00f1a de 5 a\u00f1os gravemente herida en el accidente de coche en el que se vio implicado el ex entrenador asistente Britt Reid a principios de este a\u00f1o.<\/p>\n<p>El acuerdo entre el equipo de la NFL y la familia de Ariel Young le proporcionar\u00e1 \"atenci\u00f3n m\u00e9dica de primera clase y estabilidad financiera a largo plazo\", seg\u00fan un comunicado emitido el viernes por el representante legal del equipo y el abogado de la familia.<\/p>\n<p>\"Durante los \u00faltimos meses, representantes de los Jefes de Kansas City, Ariel Young y la familia de Ariel han trabajado juntos, junto con expertos m\u00e9dicos, para desarrollar un plan para cuidar de Ariel, ahora y para el resto de su vida\", dice el comunicado.<\/p>\n<p>Young iba en uno de los dos coches golpeados por Reid, el hijo del actual entrenador jefe de los Chiefs, Andy Reid, en el lateral de una rampa de entrada a lo largo de la interestatal 435 en Kansas City el 4 de febrero.<\/p>\n<p>La colisi\u00f3n se produjo pocos d\u00edas antes de que los Chiefs jugaran la Super Bowl en Florida.<\/p>\n<p>Un an\u00e1lisis de sangre revel\u00f3 que la concentraci\u00f3n de alcohol en sangre de Reid era de 0,113, superior al l\u00edmite legal de 0,08, seg\u00fan un comunicado de prensa de la Fiscal\u00eda del condado de Jackson, Missouri. Reid conduc\u00eda a casi 84 mph segundos antes del accidente, a\u00f1adi\u00f3 el comunicado de prensa.<\/p>\n<p>Young sufri\u00f3 lesiones cerebrales traum\u00e1ticas, una fractura parietal, hematomas subdurales y contusiones cerebrales tras el accidente, seg\u00fan el comunicado de prensa.<\/p>\n<p>En el comunicado del viernes se afirmaba que Young est\u00e1 en v\u00edas de recuperaci\u00f3n y se se\u00f1alaba que hab\u00eda asistido a su primer d\u00eda de clase.<\/p>\n<p>\"La recuperaci\u00f3n de Ariel es un largo camino, pero ha hecho grandes progresos y sigue mejorando cada d\u00eda\", dice el comunicado.<\/p>\n<p>Los Chiefs permitieron que su contrato expirara al final de la temporada 2020, lo que efectivamente puso fin a su empleo con el equipo. Reid est\u00e1 a la espera de juicio por un delito grave de conducir ebrio. Se declar\u00f3 inocente en junio.<\/p>\n<p><strong>Si usted o un ser querido ha sufrido lesiones en un accidente de coche llame al <a href=\"https:\/\/northlandinjurylaw.com\/es\/abogado-de-muerte-por-negligencia-de-kansas-city\/\">Ley de lesiones de Northland<\/a> en <a href=\"tel:8164004878\">(816) 400-4878<\/a> para hablar con un <a href=\"https:\/\/northlandinjurylaw.com\/es\/abogado-de-accidentes-de-coche-en-kansas-city\/\">Missouri abogado accidente autom\u00f3vil<\/a> para obtener la indemnizaci\u00f3n que necesita.  Un abogado con experiencia en lesiones personales puede aliviar parte de la carga mediante la participaci\u00f3n en la investigaci\u00f3n de los hechos, la recopilaci\u00f3n de la documentaci\u00f3n necesaria, y la elaboraci\u00f3n de demandas concisas y exhaustivas para la soluci\u00f3n de su reclamo.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>As Northland personal injury lawyers in Kansas City, we constantly encounter clients who sustain personal injuries when involved in car accidents. As fathers first and then attorneys, it is important for us to promote driver safety. The Kansas City Chiefs announced Friday it will pay for the medical expenses for the 5-year-old girl seriously injured &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/northlandinjurylaw.com\/es\/blog\/los-kansas-city-chiefs-pagaran-los-gastos-medicos-del-nino-de-5-anos-herido-en-el-accidente-de-britt-reid\/\" class=\"more-link\">Seguir leyendo<span class=\"screen-reader-text\"> &#8220;Kansas City Chiefs To Pay Medical Expenses of 5 Year-Old Injured in Britt Reid Crash&#8221;<\/span><\/a><\/p>","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1283","post","type-post","status-publish","format-standard","hentry","category-news","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kansas City Chiefs To Pay Medical Expenses of 5 Year-Old Injured in Britt Reid Crash - Northland Injury Law<\/title>\n<meta name=\"description\" content=\"As Northland personal injury lawyers in Kansas City, we constantly encounter clients who sustain personal injuries when involved in car accidents. As fathers first and then attorneys, it is important for us to promote driver safety. The Kansas City Chiefs announced Friday it will pay for the medical expenses for the 5-year-old girl seriously injured\u2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/northlandinjurylaw.com\/es\/blog\/los-kansas-city-chiefs-pagaran-los-gastos-medicos-del-nino-de-5-anos-herido-en-el-accidente-de-britt-reid\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kansas City Chiefs To Pay Medical Expenses of 5 Year-Old Injured in Britt Reid Crash - Northland Injury Law\" \/>\n<meta property=\"og:description\" content=\"As Northland personal injury lawyers in Kansas City, we constantly encounter clients who sustain personal injuries when involved in car accidents. As fathers first and then attorneys, it is important for us to promote driver safety. The Kansas City Chiefs announced Friday it will pay for the medical expenses for the 5-year-old girl seriously injured\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/northlandinjurylaw.com\/es\/blog\/los-kansas-city-chiefs-pagaran-los-gastos-medicos-del-nino-de-5-anos-herido-en-el-accidente-de-britt-reid\/\" \/>\n<meta property=\"og:site_name\" content=\"Northland Injury Law\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/accidentinjurylawyers\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-20T12:27:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-14T07:46:56+00:00\" \/>\n<meta name=\"author\" content=\"Eric Bartlett\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eric Bartlett\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kansas City Jefes de pagar los gastos m\u00e9dicos de 5 a\u00f1os de edad, heridos en el accidente de Britt Reid - Northland Ley de Lesiones","description":"Como abogados de lesiones personales de Northland en Kansas City, nos encontramos constantemente con clientes que sufren lesiones personales cuando se ven implicados en accidentes de tr\u00e1fico. Como padres primero y abogados despu\u00e9s, es importante para nosotros promover la seguridad de los conductores. Los Jefes Kansas City anunci\u00f3 el viernes que pagar\u00e1 los gastos m\u00e9dicos de la ni\u00f1a de 5 a\u00f1os gravemente herido...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/northlandinjurylaw.com\/es\/blog\/los-kansas-city-chiefs-pagaran-los-gastos-medicos-del-nino-de-5-anos-herido-en-el-accidente-de-britt-reid\/","og_locale":"es_MX","og_type":"article","og_title":"Kansas City Chiefs To Pay Medical Expenses of 5 Year-Old Injured in Britt Reid Crash - Northland Injury Law","og_description":"As Northland personal injury lawyers in Kansas City, we constantly encounter clients who sustain personal injuries when involved in car accidents. As fathers first and then attorneys, it is important for us to promote driver safety. The Kansas City Chiefs announced Friday it will pay for the medical expenses for the 5-year-old girl seriously injured\u2026","og_url":"https:\/\/northlandinjurylaw.com\/es\/blog\/los-kansas-city-chiefs-pagaran-los-gastos-medicos-del-nino-de-5-anos-herido-en-el-accidente-de-britt-reid\/","og_site_name":"Northland Injury Law","article_publisher":"https:\/\/www.facebook.com\/accidentinjurylawyers\/","article_published_time":"2021-11-20T12:27:27+00:00","article_modified_time":"2024-06-14T07:46:56+00:00","author":"Eric Bartlett","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eric Bartlett","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/northlandinjurylaw.com\/blog\/kansas-city-chiefs-to-pay-medical-expenses-of-5-year-old-injured-in-britt-reid-crash\/#article","isPartOf":{"@id":"https:\/\/northlandinjurylaw.com\/blog\/kansas-city-chiefs-to-pay-medical-expenses-of-5-year-old-injured-in-britt-reid-crash\/"},"author":{"name":"Eric Bartlett","@id":"https:\/\/northlandinjurylaw.com\/#\/schema\/person\/1e35848aa80e77f1c0b4159d4073bc20"},"headline":"Kansas City Chiefs To Pay Medical Expenses of 5 Year-Old Injured in Britt Reid Crash","datePublished":"2021-11-20T12:27:27+00:00","dateModified":"2024-06-14T07:46:56+00:00","mainEntityOfPage":{"@id":"https:\/\/northlandinjurylaw.com\/blog\/kansas-city-chiefs-to-pay-medical-expenses-of-5-year-old-injured-in-britt-reid-crash\/"},"wordCount":423,"commentCount":0,"publisher":{"@id":"https:\/\/northlandinjurylaw.com\/#organization"},"articleSection":["News"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/northlandinjurylaw.com\/blog\/kansas-city-chiefs-to-pay-medical-expenses-of-5-year-old-injured-in-britt-reid-crash\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/northlandinjurylaw.com\/blog\/kansas-city-chiefs-to-pay-medical-expenses-of-5-year-old-injured-in-britt-reid-crash\/","url":"https:\/\/northlandinjurylaw.com\/blog\/kansas-city-chiefs-to-pay-medical-expenses-of-5-year-old-injured-in-britt-reid-crash\/","name":"Kansas City Jefes de pagar los gastos m\u00e9dicos de 5 a\u00f1os de edad, heridos en el accidente de Britt Reid - Northland Ley de Lesiones","isPartOf":{"@id":"https:\/\/northlandinjurylaw.com\/#website"},"datePublished":"2021-11-20T12:27:27+00:00","dateModified":"2024-06-14T07:46:56+00:00","description":"Como abogados de lesiones personales de Northland en Kansas City, nos encontramos constantemente con clientes que sufren lesiones personales cuando se ven implicados en accidentes de tr\u00e1fico. Como padres primero y abogados despu\u00e9s, es importante para nosotros promover la seguridad de los conductores. Los Jefes Kansas City anunci\u00f3 el viernes que pagar\u00e1 los gastos m\u00e9dicos de la ni\u00f1a de 5 a\u00f1os gravemente herido...","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/northlandinjurylaw.com\/blog\/kansas-city-chiefs-to-pay-medical-expenses-of-5-year-old-injured-in-britt-reid-crash\/"]}]},{"@type":"WebSite","@id":"https:\/\/northlandinjurylaw.com\/#website","url":"https:\/\/northlandinjurylaw.com\/","name":"Ley de lesiones de Northland","description":"","publisher":{"@id":"https:\/\/northlandinjurylaw.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/northlandinjurylaw.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/northlandinjurylaw.com\/#organization","name":"Ley de lesiones de Northland","url":"https:\/\/northlandinjurylaw.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/northlandinjurylaw.com\/#\/schema\/logo\/image\/","url":"https:\/\/northlandinjurylaw.com\/wp-content\/uploads\/2024\/05\/logo.jpg","contentUrl":"https:\/\/northlandinjurylaw.com\/wp-content\/uploads\/2024\/05\/logo.jpg","width":415,"height":103,"caption":"Northland Injury Law"},"image":{"@id":"https:\/\/northlandinjurylaw.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/accidentinjurylawyers\/","https:\/\/www.linkedin.com\/company\/northland-injury-law","https:\/\/www.instagram.com\/northlandinjurylaw\/","https:\/\/www.youtube.com\/@northlandinjurylaw4755","https:\/\/www.yelp.com\/biz\/northland-injury-law-kansas-city","https:\/\/www.lawinfo.com\/lawfirm\/missouri\/kansas-city\/northland-injury-law\/ca10cabc-467c-446b-bfc0-f673053baf63.html","https:\/\/profiles.superlawyers.com\/missouri\/kansas-city\/lawfirm\/northland-injury-law\/ca10cabc-467c-446b-bfc0-f673053baf63.html","https:\/\/lawyers.findlaw.com\/profile\/view\/2362635_1","https:\/\/reviews.birdeye.com\/northland-injury-law-164779247415291","https:\/\/localspark.com\/listings\/legal-services\/kansas-city-mo\/northland-injury-law-5600-ne-antioch-rd-kansas-city-mo-64119\/","https:\/\/www.zoominfo.com\/p\/Stephen-Mowry\/126980529","https:\/\/www.datanyze.com\/companies\/northland-injury-law\/358568082"]},{"@type":"Person","@id":"https:\/\/northlandinjurylaw.com\/#\/schema\/person\/1e35848aa80e77f1c0b4159d4073bc20","name":"Eric Bartlett","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bf253cf71e20f6e1cffd8b8f42de35214279011bf47dbcb56d2ffc79a4f5d414?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf253cf71e20f6e1cffd8b8f42de35214279011bf47dbcb56d2ffc79a4f5d414?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf253cf71e20f6e1cffd8b8f42de35214279011bf47dbcb56d2ffc79a4f5d414?s=96&d=mm&r=g","caption":"Eric Bartlett"},"url":"https:\/\/northlandinjurylaw.com\/es\/author\/eric-bartlett-2\/"}]}},"_links":{"self":[{"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/posts\/1283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/comments?post=1283"}],"version-history":[{"count":3,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/posts\/1283\/revisions"}],"predecessor-version":[{"id":3383,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/posts\/1283\/revisions\/3383"}],"wp:attachment":[{"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/media?parent=1283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/categories?post=1283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/northlandinjurylaw.com\/es\/wp-json\/wp\/v2\/tags?post=1283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}